{"id":6312,"date":"2023-12-15T07:25:30","date_gmt":"2023-12-15T07:25:30","guid":{"rendered":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/"},"modified":"2024-10-30T19:53:36","modified_gmt":"2024-10-30T18:53:36","slug":"cart","status":"publish","type":"page","link":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6312\" class=\"elementor elementor-6312\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ed6969 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ed6969\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61de5f5\" data-id=\"61de5f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09e93de elementor-align-center elementor-tablet-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"09e93de\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-lg\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-podcast\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HYBRID EVENTS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7673023 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7673023\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Shopping basket<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45733ee custom-cart-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45733ee\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-620efdf\" data-id=\"620efdf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>HYBRIDE EVENTS Shopping Cart Remove item Thumbnail image Product Price Quantity Subtotal \u00d7 EUTECH Themenreisen Nuremberg 80,00\u20ac EUTECH Themenreisen Nuremberg quantity 160,00\u20ac Cart Totals Subtotal 160,00\u20ac Coupon: emetnum100 -160,00\u20ac [Remove] Total 0,00\u20ac Proceed to Checkout<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"class_list":["post-6312","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cart - Themenreisen EUTECH<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cart - Themenreisen EUTECH\" \/>\n<meta property=\"og:description\" content=\"HYBRIDE EVENTS Warenkorb Remove item Thumbnail image Product Price Quantity Subtotal &times; EUTECH Themenreisen Nuremberg 80,00&euro; EUTECH Themenreisen Nuremberg quantity 160,00&euro; Cart Totals Subtotal 160,00&euro; Coupon: emetnum100 -160,00&euro; [Remove] Total 0,00&euro; Proceed to Checkout\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/cart\/\" \/>\n<meta property=\"og:site_name\" content=\"Themenreisen EUTECH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T18:53:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/\",\"url\":\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/\",\"name\":\"Cart - Themenreisen EUTECH\",\"isPartOf\":{\"@id\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png\",\"datePublished\":\"2023-12-15T07:25:30+00:00\",\"dateModified\":\"2024-10-30T18:53:36+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#primaryimage\",\"url\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png\",\"contentUrl\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website\",\"url\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/\",\"name\":\"Themenreisen EUTECH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cart - Themenreisen EUTECH","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Cart - Themenreisen EUTECH","og_description":"HYBRIDE EVENTS Warenkorb Remove item Thumbnail image Product Price Quantity Subtotal &times; EUTECH Themenreisen Nuremberg 80,00&euro; EUTECH Themenreisen Nuremberg quantity 160,00&euro; Cart Totals Subtotal 160,00&euro; Coupon: emetnum100 -160,00&euro; [Remove] Total 0,00&euro; Proceed to Checkout","og_url":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/cart\/","og_site_name":"Themenreisen EUTECH","article_modified_time":"2024-10-30T18:53:36+00:00","og_image":[{"url":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/","url":"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/","name":"Cart - Themenreisen EUTECH","isPartOf":{"@id":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#primaryimage"},"image":{"@id":"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#primaryimage"},"thumbnailUrl":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png","datePublished":"2023-12-15T07:25:30+00:00","dateModified":"2024-10-30T18:53:36+00:00","breadcrumb":{"@id":"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#primaryimage","url":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png","contentUrl":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/12\/Event-Logo-03-e1689347313868-300x300.png"},{"@type":"BreadcrumbList","@id":"http:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/cart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/"},{"@type":"ListItem","position":2,"name":"Cart"}]},{"@type":"WebSite","@id":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website","url":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/","name":"Themenreisen EUTECH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages\/6312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/comments?post=6312"}],"version-history":[{"count":79,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages\/6312\/revisions"}],"predecessor-version":[{"id":10949,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages\/6312\/revisions\/10949"}],"wp:attachment":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/media?parent=6312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}