{"id":9677,"date":"2024-09-02T16:26:06","date_gmt":"2024-09-02T14:26:06","guid":{"rendered":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/?page_id=9677"},"modified":"2024-11-06T21:20:36","modified_gmt":"2024-11-06T20:20:36","slug":"esg-register-nuremberg","status":"publish","type":"page","link":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/esg-register-nuremberg\/","title":{"rendered":"Esg Register Nuremberg"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9677\" class=\"elementor elementor-9677\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5b9e6d elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5b9e6d\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de28cae\" data-id=\"de28cae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0b3e35 elementor-align-center elementor-tablet-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"b0b3e35\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-lg\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-podcast\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PHYSICAL EVENTS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a763d8 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3a763d8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span style=\"color:#01244d\">Sustainability theme trip<br> Nuremberg<\/span> Registration<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d7a2cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d7a2cf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-397be8f\" data-id=\"397be8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4acf1c elementor-widget-divider--view-line_text elementor-widget-divider--element-align-right elementor-widget elementor-widget-divider\" data-id=\"d4acf1c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h5 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tTechnology Obliges\t\t\t\t<\/h5>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-544cb77 elementor-widget elementor-widget-elementskit-heading\" data-id=\"544cb77\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\"><span><span>Registration fees<\/span><\/span><\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db3992b elementor-widget elementor-widget-text-editor\" data-id=\"db3992b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tRegister today and secure your tickets for the 'Themed Series' event in Nuremberg before they sell out! Don't miss the opportunity to be there.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e5fdced elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5fdced\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e6acc6\" data-id=\"0e6acc6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcb8d22 elementor-view-stacked elementor-widget__width-initial elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"fcb8d22\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-protected-content-v2\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a0c111 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7a0c111\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">01.<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63644fc animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"63644fc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Option 1<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df1ebf8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"df1ebf8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Normal price<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc83488 elementor-widget elementor-widget-text-editor\" data-id=\"fc83488\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"ui-provider ee bfm bfn bfo bfp bfq bfr bfs bft bfu bfv bfw bfx bfy bfz bga bgb bgc bgd bge bgf bgg bgh bgi bgj bgk bgl bgm bgn bgo bgp bgq bgr bgs bgt\" dir=\"ltr\">The admission ticket grants access to the event, all lectures and refreshing drinks.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d744bbe elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d744bbe\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u20ac80<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaa5a58 elementor-align-center elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"eaa5a58\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-float\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/shop\/?add-to-cart=9596\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Buy Ticket<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0a6e026\" data-id=\"0a6e026\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af44f49 elementor-view-stacked elementor-widget__width-initial elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"af44f49\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-badge\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f60b08a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f60b08a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">02.<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1afbd68 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1afbd68\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Option 2<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3518efb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3518efb\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Discount price<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f600e elementor-widget elementor-widget-text-editor\" data-id=\"59f600e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"ui-provider ee bfm bfn bfo bfp bfq bfr bfs bft bfu bfv bfw bfx bfy bfz bga bgb bgc bgd bge bgf bgg bgh bgi bgj bgk bgl bgm bgn bgo bgp bgq bgr bgs bgt\" dir=\"ltr\">To take advantage of the exclusive discount, please enter your voucher code here<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4097f5 elementor-widget elementor-widget-shortcode\" data-id=\"c4097f5\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">    <style>\r\n        #coupon-message.success { border-color:green; }\r\n        #coupon-message.error { border-color:red; }\r\n        #coupon-message { margin-top:-50px; font-size: 14px; padding: 10px 20px; margin-bottom: 10px; border: 1px solid black; font-weight: 500; text-align: center; display:none; }\r\n        #coupon { text-align:center; }\r\n    <\/style>\r\n    <form class=\"main-section\" id=\"coupon-code-form\" action=\"https:\/\/themenreisen.eutech.org\" data-trp-original-action=\"https:\/\/themenreisen.eutech.org\">\r\n        <div id=\"coupon-message\" class=\"success\"><\/div>\r\n        <input placeholder=\"Enter Coupon Code\" class=\"field-section\" type=\"text\" id=\"coupon\" name=\"coupon\" value=\"\"><br>\r\n        <input type=\"hidden\" name=\"ticket_direct\" value=\"1\">\r\n        <input type=\"hidden\" name=\"quantity\" value=\"1\">\r\n        <input type=\"hidden\" name=\"add-to-cart\" value=\"9596\">\r\n        <input class=\"off-button\" type=\"submit\" value=\"Buy Ticket\">\r\n    <input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\r\n    <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9b114a0\" data-id=\"9b114a0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d739131 elementor-view-stacked elementor-widget__width-initial elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"d739131\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-user\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22e1e0d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"22e1e0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">03.<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a9d297 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4a9d297\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Option 3<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b6784e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1b6784e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">EUTECH Partner<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55fe340 elementor-widget elementor-widget-text-editor\" data-id=\"55fe340\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tPartners (members) can receive free tickets. Enter your membership number.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25c874d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"25c874d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FREE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2b6176 elementor-align-center elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"c2b6176\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-float\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/eutech-themenreisen-registration-form-german-nurmberg\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Register<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0427494 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0427494\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-28742bf elementor-hidden-tablet\" data-id=\"28742bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ede409a\" data-id=\"ede409a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725141c elementor-view-stacked elementor-widget__width-initial elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"725141c\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-screen\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a32c72 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0a32c72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">04.<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c93840 animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7c93840\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">physical events<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84feade elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"84feade\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Online stream<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c4615a elementor-widget elementor-widget-text-editor\" data-id=\"2c4615a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Anyone around the globe can stream our live broadcast absolutely free of charge. Register to receive the streaming URL.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6384fd9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6384fd9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FREE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fcbf04 elementor-align-center elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"6fcbf04\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-float\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/themenreisen-hannover-online\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Register<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-816d4fb\" data-id=\"816d4fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f7d7d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f7d7d5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a864f16\" data-id=\"a864f16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db0d169 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-right elementor-widget elementor-widget-divider\" data-id=\"db0d169\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<h5 class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tTechnology Obliges\t\t\t\t<\/h5>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b3660b elementor-widget elementor-widget-elementskit-heading\" data-id=\"2b3660b\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Events <span><span>GALLERY<\/span><\/span><\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f915221 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f915221\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e78c7e6\" data-id=\"e78c7e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12f3661 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"12f3661\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">SDG Awards 2022 - 2023<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Valuing Natural Capital Conference 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">LATAM Edge Virtual Expo &amp; Awards 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Climate Action Global Summit &amp; Expo 2022<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">SDG Awards 2021<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-99269cd\" data-id=\"99269cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc44e4a elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dc44e4a\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">EU China Economy &amp; Technology Expo 2021<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Virtual Investment Forum 2021<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Building in Existing Contexts 2023<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Karlsruhe Contaminated Sites Seminar 2023<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">EU Tech Forum - Tech &amp; Lederhose 2023 <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b145fb elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-widget elementor-widget-slides\" data-id=\"9b145fb\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-2e0f198 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-0d6f7cc swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-198b546 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-c8746ee swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-d40bd95 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-22c33d6 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-797425b swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5320d55 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-2c523f3 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-1233d46 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-06d84d4 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-4bf07a7 swiper-slide\"><div class=\"swiper-slide-bg\" role=\"img\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next slide<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d882ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d882ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0a06977\" data-id=\"0a06977\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c011adc elementor-widget elementor-widget-gallery\" data-id=\"c011adc\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:6,&quot;columns_tablet&quot;:5,&quot;columns_mobile&quot;:3,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-20.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (20)\" data-elementor-lightbox-description=\"EUTECH-THEMENREISEN-Hannover\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc4MywidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci0yMC5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-20.jpg\" data-width=\"1320\" data-height=\"880\" aria-label=\"EUTECH-THEMENREISEN-Hannover\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-62.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (62)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc2MiwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci02Mi5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-62.jpg\" data-width=\"1320\" data-height=\"880\" aria-label=\"EUTECH-THEMENREISEN-Hannover\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-6-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-themenreisen-sustainability-and-competitiveness (6)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ3NiwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMVwvZXV0ZWNoLXRoZW1lbnJlaXNlbi1zdXN0YWluYWJpbGl0eS1hbmQtY29tcGV0aXRpdmVuZXNzLTYtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImFsbC1jMDExYWRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-6-scaled.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-topic-travel-sustainability-and-competitiveness\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/10\/eutech-forum-event-2023_5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-forum-event-2023_5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDU1NiwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8xMFwvZXV0ZWNoLWZvcnVtLWV2ZW50LTIwMjNfNS5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/10\/eutech-forum-event-2023_5.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-forum-event-2023\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-12.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (12)\" data-elementor-lightbox-description=\"EUTECH-THEMENREISEN-Hannover\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3MiwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci0xMi5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-12.jpg\" data-width=\"1320\" data-height=\"880\" aria-label=\"EUTECH-THEMENREISEN-Hannover\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-2-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-themenreisen-sustainability-and-competitiveness (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ3MiwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMVwvZXV0ZWNoLXRoZW1lbnJlaXNlbi1zdXN0YWluYWJpbGl0eS1hbmQtY29tcGV0aXRpdmVuZXNzLTItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImFsbC1jMDExYWRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-2-scaled.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-topic-travel-sustainability-and-competitiveness\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/10\/eutech-forum-event-2023_45.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-forum-event-2023_45\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxNSwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8xMFwvZXV0ZWNoLWZvcnVtLWV2ZW50LTIwMjNfNDUuanBnIiwic2xpZGVzaG93IjoiYWxsLWMwMTFhZGMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/10\/eutech-forum-event-2023_45.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-forum-event-2023_45\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-12-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-themenreisen-sustainability-and-competitiveness (12)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ4MywidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMVwvZXV0ZWNoLXRoZW1lbnJlaXNlbi1zdXN0YWluYWJpbGl0eS1hbmQtY29tcGV0aXRpdmVuZXNzLTEyLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-12-scaled.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-topic-travel-sustainability-and-competitiveness\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-25.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (25)\" data-elementor-lightbox-description=\"EUTECH-THEMENREISEN-Hannover\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc4NSwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci0yNS5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-25.jpg\" data-width=\"1320\" data-height=\"880\" aria-label=\"EUTECH-THEMENREISEN-Hannover\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-3-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-themenreisen-sustainability-and-competitiveness (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ3MywidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMVwvZXV0ZWNoLXRoZW1lbnJlaXNlbi1zdXN0YWluYWJpbGl0eS1hbmQtY29tcGV0aXRpdmVuZXNzLTMtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImFsbC1jMDExYWRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-3-scaled.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-topic-travel-sustainability-and-competitiveness\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-1-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-themenreisen-sustainability-and-competitiveness (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ3MSwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMVwvZXV0ZWNoLXRoZW1lbnJlaXNlbi1zdXN0YWluYWJpbGl0eS1hbmQtY29tcGV0aXRpdmVuZXNzLTEtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImFsbC1jMDExYWRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-1-scaled.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-topic-travel-sustainability-and-competitiveness\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-38.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (38)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzczMywidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci0zOC5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-38.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"EUTECH-THEMENREISEN-Hannover\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/10\/eutech-forum-event-2023_50.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-forum-event-2023_50\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDUxMCwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8xMFwvZXV0ZWNoLWZvcnVtLWV2ZW50LTIwMjNfNTAuanBnIiwic2xpZGVzaG93IjoiYWxsLWMwMTFhZGMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/10\/eutech-forum-event-2023_50.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-forum-event-2023_50\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-11-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"eutech-themenreisen-sustainability-and-competitiveness (11)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjQ4MiwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMVwvZXV0ZWNoLXRoZW1lbnJlaXNlbi1zdXN0YWluYWJpbGl0eS1hbmQtY29tcGV0aXRpdmVuZXNzLTExLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/01\/eutech-themenreisen-sustainability-and-competitiveness-11-scaled.jpg\" data-width=\"1350\" data-height=\"900\" aria-label=\"eutech-topic-travel-sustainability-and-competitiveness\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/07\/Capture7.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"Capture7.jpg\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkxMSwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wN1wvQ2FwdHVyZTcuanBnIiwic2xpZGVzaG93IjoiYWxsLWMwMTFhZGMifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2023\/07\/Capture7.jpg\" data-width=\"1045\" data-height=\"543\" aria-label=\"Capture7.jpg\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc0NywidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci0zLmpwZyIsInNsaWRlc2hvdyI6ImFsbC1jMDExYWRjIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-3.jpg\" data-width=\"1320\" data-height=\"880\" aria-label=\"EUTECH-THEMENREISEN-Hannover (3)\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-10.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (10)\" data-elementor-lightbox-description=\"EUTECH-THEMENREISEN-Hannover\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc3MCwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci0xMC5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-10.jpg\" data-width=\"1320\" data-height=\"880\" aria-label=\"EUTECH-THEMENREISEN-Hannover\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-64.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"all-c011adc\" data-elementor-lightbox-title=\"EUTECH-THEMENREISEN-Hannover (64)\" data-elementor-lightbox-description=\"EUTECH-THEMENREISEN-Hannover\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Nzc2NCwidXJsIjoiaHR0cHM6XC9cL3Rlc3QtdGhlbWVucmVpc2VuLWV1dGVjaC13b3JkcHJlc3MucnoubXVwLWRpZ2l0YWwuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRVVURUNILVRIRU1FTlJFSVNFTi1IYW5ub3Zlci02NC5qcGciLCJzbGlkZXNob3ciOiJhbGwtYzAxMWFkYyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/wp-content\/uploads\/2024\/03\/EUTECH-THEMENREISEN-Hannover-64.jpg\" data-width=\"1320\" data-height=\"880\" aria-label=\"EUTECH-THEMENREISEN-Hannover\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>PHYSICAL EVENTS Themed Journey Sustainability Nuremberg Registration Technology Mandatory Registration Fees Register today and secure your tickets for the 'Themed Journeys' event in Nuremberg before they sell out! Don't miss the opportunity to be there. 01. Option 1 Normal price The admission ticket grants access to the event, all presentations and refreshing drinks. \u20ac80 ticket [...]<\/p>","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"rank_math_lock_modified_date":false,"footnotes":""},"class_list":["post-9677","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esg Register Nuremberg - Themenreisen EUTECH<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esg Register Nuremberg - Themenreisen EUTECH\" \/>\n<meta property=\"og:description\" content=\"PHYSICAL EVENTS Themenreise Nachhaltigkeit N\u00fcrnberg Registrierung Technologie Verpflichtet Registrierungsgeb\u00fchren Registrieren Sie sich heute und sichern Sie sich Ihre Tickets f\u00fcr das &#8216;Themenreisen&#8217; Event in N\u00fcrnberg bevor sie ausverkauft sind! Verpassen Sie nicht die Gelegenheit, dabei zu sein. 01. Option 1 Normalpreis Das Eintrittsticket gew\u00e4hrt Zugang zur Veranstaltung, zu s\u00e4mtlichen Vortr\u00e4gen sowie erfrischenden Getr\u00e4nken. \u20ac80 Ticket [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/esg-register-nuremberg\/\" \/>\n<meta property=\"og:site_name\" content=\"Themenreisen EUTECH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T20:20:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/\",\"url\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/\",\"name\":\"Esg Register Nuremberg - Themenreisen EUTECH\",\"isPartOf\":{\"@id\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website\"},\"datePublished\":\"2024-09-02T14:26:06+00:00\",\"dateModified\":\"2024-11-06T20:20:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esg Register Nuremberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website\",\"url\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/\",\"name\":\"Themenreisen EUTECH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esg Register Nuremberg - Themenreisen EUTECH","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Esg Register Nuremberg - Themenreisen EUTECH","og_description":"PHYSICAL EVENTS Themenreise Nachhaltigkeit N\u00fcrnberg Registrierung Technologie Verpflichtet Registrierungsgeb\u00fchren Registrieren Sie sich heute und sichern Sie sich Ihre Tickets f\u00fcr das &#8216;Themenreisen&#8217; Event in N\u00fcrnberg bevor sie ausverkauft sind! Verpassen Sie nicht die Gelegenheit, dabei zu sein. 01. Option 1 Normalpreis Das Eintrittsticket gew\u00e4hrt Zugang zur Veranstaltung, zu s\u00e4mtlichen Vortr\u00e4gen sowie erfrischenden Getr\u00e4nken. \u20ac80 Ticket [&hellip;]","og_url":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/esg-register-nuremberg\/","og_site_name":"Themenreisen EUTECH","article_modified_time":"2024-11-06T20:20:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/","url":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/","name":"Esg Register Nuremberg - Themenreisen EUTECH","isPartOf":{"@id":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website"},"datePublished":"2024-09-02T14:26:06+00:00","dateModified":"2024-11-06T20:20:36+00:00","breadcrumb":{"@id":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/esg-register-nuremberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/"},{"@type":"ListItem","position":2,"name":"Esg Register Nuremberg"}]},{"@type":"WebSite","@id":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/#website","url":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/","name":"Themenreisen EUTECH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages\/9677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/comments?post=9677"}],"version-history":[{"count":53,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages\/9677\/revisions"}],"predecessor-version":[{"id":11384,"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/pages\/9677\/revisions\/11384"}],"wp:attachment":[{"href":"https:\/\/test-themenreisen-eutech-wordpress.rz.mup-digital.com\/en\/wp-json\/wp\/v2\/media?parent=9677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}